{"id":330,"count":1,"description":"","link":"https:\/\/soymigrante.com\/revista\/tag\/especial-del-mes-patrio\/","name":"Especial del Mes Patrio","slug":"especial-del-mes-patrio","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/soymigrante.com\/revista\/tag\/especial-del-mes-patrio\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\n\t\t<link rel=\"preconnect\" href=\"https:\/\/fonts.googleapis.com\" crossorigin>\n<link rel=\"preconnect\" href=\"https:\/\/fonts.gstatic.com\" crossorigin>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"SoyMigrante.com REVISTA \u2013 Nuestra misi\u00f3n es reconocer y dignificar al migrante.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Especial del Mes Patrio\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/soymigrante.com\/revista\/tag\/especial-del-mes-patrio\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2024\/11\/SoyMigrantecom-V-color-112x112-1.webp\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2024\/11\/SoyMigrantecom-V-color-112x112-1.webp\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/soymigrantecom\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@SoyMigrante_com\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Especial del Mes Patrio\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2024\/11\/SoyMigrantecom-V-color-112x112-1.webp\" \/>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Especial del Mes Patrio<\/title>\n\n","aioseo_head_json":{"title":"Especial del Mes Patrio","description":"","canonical_url":"https:\/\/soymigrante.com\/revista\/tag\/especial-del-mes-patrio\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":"&lt;link rel=\"preconnect\" href=\"https:\/\/fonts.googleapis.com\" crossorigin&gt;\n&lt;link rel=\"preconnect\" href=\"https:\/\/fonts.gstatic.com\" crossorigin&gt;"},"schema":null,"og:locale":"es_ES","og:site_name":"SoyMigrante.com REVISTA \u2013 Nuestra misi\u00f3n es reconocer y dignificar al migrante.","og:type":"article","og:title":"Especial del Mes Patrio","og:url":"https:\/\/soymigrante.com\/revista\/tag\/especial-del-mes-patrio\/","og:image":"https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2024\/11\/SoyMigrantecom-V-color-112x112-1.webp","og:image:secure_url":"https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2024\/11\/SoyMigrantecom-V-color-112x112-1.webp","article:publisher":"https:\/\/www.facebook.com\/soymigrantecom","twitter:card":"summary_large_image","twitter:site":"@SoyMigrante_com","twitter:title":"Especial del Mes Patrio","twitter:image":"https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2024\/11\/SoyMigrantecom-V-color-112x112-1.webp"},"aioseo_meta_data":{"term_id":"330","title":null,"description":null,"keywords":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"pillar_content":null,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2026-09-01 21:45:59","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"breadcrumb_settings":null,"created":"2026-09-01 21:45:53","updated":"2026-09-01 21:45:59"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/soymigrante.com\/revista\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\tEspecial del Mes Patrio\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/soymigrante.com\/revista"},{"label":"Especial del Mes Patrio","link":"https:\/\/soymigrante.com\/revista\/tag\/especial-del-mes-patrio\/"}],"_links":{"self":[{"href":"https:\/\/soymigrante.com\/revista\/wp-json\/wp\/v2\/tags\/330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soymigrante.com\/revista\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/soymigrante.com\/revista\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/soymigrante.com\/revista\/wp-json\/wp\/v2\/posts?tags=330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}