{"id":57424,"date":"2026-06-03T10:09:29","date_gmt":"2026-06-03T16:09:29","guid":{"rendered":"https:\/\/soymigrante.com\/revista\/?p=57424"},"modified":"2026-06-03T10:14:27","modified_gmt":"2026-06-03T16:14:27","slug":"obispos-de-usa-piden-al-congreso-transformar-abordaje-migratorio-y-frenar-la-separacion-de-familias","status":"publish","type":"post","link":"https:\/\/soymigrante.com\/revista\/obispos-de-usa-piden-al-congreso-transformar-abordaje-migratorio-y-frenar-la-separacion-de-familias\/","title":{"rendered":"Obispos de USA piden al Congreso transformar abordaje migratorio y frenar la separaci\u00f3n de familias"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"57424\" class=\"elementor elementor-57424\" data-elementor-post-type=\"post\">\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-2d5248a e-flex e-con-boxed e-con e-parent\" data-id=\"2d5248a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cd1833a elementor-widget elementor-widget-heading\" data-id=\"cd1833a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Obispos de Estados Unidos piden al Congreso limitar fondos para deportaciones, reforzar protecci\u00f3n a familias migrantes y emprender una transformaci\u00f3n del sistema migratorio.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-dd90b6f e-flex e-con-boxed e-con e-parent\" data-id=\"dd90b6f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-62626bc elementor-widget elementor-widget-text-editor\" data-id=\"62626bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u201cDadas las circunstancias y la financiaci\u00f3n sin precedentes para la aplicaci\u00f3n de las leyes migratorias y la detenci\u00f3n proporcionada por la legislaci\u00f3n aprobada el a\u00f1o pasado, pedimos nuevamente al Congreso que limite cualquier aumento adicional de fondos para estos prop\u00f3sitos\u201d.<\/p><p>Con esa petici\u00f3n, el obispo Brendan J. Cahill, secretario de la Conferencia de Obispos Cat\u00f3licos de Estados Unidos (USCCB) y presidente de su Comit\u00e9 de Migraci\u00f3n, intervino en uno de los debates m\u00e1s importantes que enfrenta actualmente Washington: c\u00f3mo distribuir los recursos federales destinados a la pol\u00edtica migratoria durante el a\u00f1o fiscal 2027.<\/p><p>La carta fue enviada a los l\u00edderes republicanos y dem\u00f3cratas de los comit\u00e9s de asignaciones presupuestarias del Senado y la C\u00e1mara de Representantes, en momentos en que el Congreso eval\u00faa solicitudes de financiamiento relacionadas con el <a href=\"https:\/\/en.wikipedia.org\/wiki\/United_States_Department_of_Homeland_Security\" target=\"_blank\" rel=\"noopener\">Departamento de Seguridad Nacional (DHS)<\/a>. A lo largo del documento, los obispos piden reforzar programas para refugiados, beneficiarios de DACA, menores migrantes y v\u00edctimas de trata, al tiempo que expresan preocupaci\u00f3n por la expansi\u00f3n de las capacidades de detenci\u00f3n y deportaci\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-5357c5f e-flex e-con-boxed e-con e-parent\" data-id=\"5357c5f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6d1328f elementor-widget elementor-widget-image\" data-id=\"6d1328f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2026\/06\/migrantes-detenidos-operativos-antimigrantes-1140x760.jpg\" class=\"attachment-large size-large wp-image-57429\" alt=\"Los obispos estadounidenses afirman que sus peticiones se basan en las acciones observadas durante el a\u00f1o fiscal 2025-26 en materia de operativos antimigrantes, en los cuales han sido detenidos muchos padres de famlia sin antecedentes penales, con la consiguiente separaci\u00f3n de familias.\" srcset=\"https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2026\/06\/migrantes-detenidos-operativos-antimigrantes-1140x760.jpg 1140w, https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2026\/06\/migrantes-detenidos-operativos-antimigrantes-300x200.jpg 300w, https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2026\/06\/migrantes-detenidos-operativos-antimigrantes-768x512.jpg 768w, https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2026\/06\/migrantes-detenidos-operativos-antimigrantes-750x500.jpg 750w, https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2026\/06\/migrantes-detenidos-operativos-antimigrantes.jpg 1262w\" sizes=\"(max-width: 768px) 100vw, 768px\" title=\"Los obispos estadounidenses afirman que sus peticiones se basan en las acciones observadas durante el a\u00f1o fiscal 2025-26 en materia de operativos antimigrantes, en los cuales han sido detenidos muchos padres de famlia sin antecedentes penales, con la consiguiente separaci\u00f3n de familias. \u2013 SoyMigrante.com REVISTA\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Los obispos estadounidenses afirman que sus peticiones se basan en las acciones observadas durante el a\u00f1o fiscal 2025-26 en materia de operativos antimigrantes, en los cuales han sido detenidos muchos padres de famlia sin antecedentes penales, con la consiguiente separaci\u00f3n de familias.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-09d709e e-flex e-con-boxed e-con e-parent\" data-id=\"09d709e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-740257c elementor-widget elementor-widget-text-editor\" data-id=\"740257c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000; font-family: Mulish, sans-serif; font-size: 29px; font-weight: bold;\">Rechazo a ret\u00f3ricas deshumanizantes\u00a0<\/span><\/p><p>Cahill inicia la carta recordando que detr\u00e1s de las estad\u00edsticas y los debates pol\u00edticos existen personas y familias cuyas vidas son afectadas por las decisiones gubernamentales. \u201cLa migraci\u00f3n es fundamentalmente acerca del movimiento de personas humanas\u201d, escribi\u00f3 el obispo.<\/p><p>Pero esta realidad suele quedar relegada en las discusiones p\u00fablicas sobre inmigraci\u00f3n: \u201cCon demasiada frecuencia, esta realidad es ignorada o descartada por completo, dando lugar a ret\u00f3ricas deshumanizantes y respuestas pol\u00edticas que no promueven el bien com\u00fan\u201d, afirm\u00f3.<\/p><p>La carta sostiene que las pol\u00edticas migratorias deben equilibrar la aplicaci\u00f3n de la ley con el respeto a la dignidad humana y la protecci\u00f3n de las poblaciones m\u00e1s vulnerables.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-677bf27 e-flex e-con-boxed e-con e-parent\" data-id=\"677bf27\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-21e9895 elementor-widget elementor-widget-image\" data-id=\"21e9895\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"577\" src=\"https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2026\/06\/brendan-cahill-obispo-de-victoria-texas-secretario-de-la-conferencia-episcopal-usa-1140x856.jpg\" class=\"attachment-large size-large wp-image-57431\" alt=\"El obispo Brendan Cahill, de Victoria, Texas es quien suscribe la carta enviada a congresistas republicanos y dem\u00f3cratas del comit\u00e9 de apropiaciones del Congreso, de cara a las solicitudes de m\u00e1s presupuesto para operativos de deportaci\u00f3n para el pr\u00f3ximo presupuesto.\" srcset=\"https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2026\/06\/brendan-cahill-obispo-de-victoria-texas-secretario-de-la-conferencia-episcopal-usa-1140x856.jpg 1140w, https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2026\/06\/brendan-cahill-obispo-de-victoria-texas-secretario-de-la-conferencia-episcopal-usa-300x225.jpg 300w, https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2026\/06\/brendan-cahill-obispo-de-victoria-texas-secretario-de-la-conferencia-episcopal-usa-768x577.jpg 768w, https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2026\/06\/brendan-cahill-obispo-de-victoria-texas-secretario-de-la-conferencia-episcopal-usa-750x563.jpg 750w, https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2026\/06\/brendan-cahill-obispo-de-victoria-texas-secretario-de-la-conferencia-episcopal-usa.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" title=\"El obispo Brendan Cahill, de Victoria, Texas es quien suscribe la carta enviada a congresistas republicanos y dem\u00f3cratas del comit\u00e9 de apropiaciones del Congreso, de cara a las solicitudes de m\u00e1s presupuesto para operativos de deportaci\u00f3n para el pr\u00f3ximo presupuesto. \u2013 SoyMigrante.com REVISTA\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">El obispo Brendan Cahill, de Victoria, Texas es quien suscribe la carta enviada a congresistas republicanos y dem\u00f3cratas del comit\u00e9 de apropiaciones del Congreso, de cara a las solicitudes de m\u00e1s presupuesto para operativos de deportaci\u00f3n para el pr\u00f3ximo presupuesto.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-91ca720 e-flex e-con-boxed e-con e-parent\" data-id=\"91ca720\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-872a9a7 elementor-widget elementor-widget-text-editor\" data-id=\"872a9a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000; font-family: Mulish, sans-serif; font-size: 29px; font-weight: bold;\">Trabajadores enfrentan incertidumbre migratoria<\/span><\/p><p>Uno de los primeros llamados de los obispos se refiere a los trabajadores religiosos extranjeros que sirven en comunidades estadounidenses. Cahill solicit\u00f3 que el Congreso otorgue una autorizaci\u00f3n permanente al programa de visas para trabajadores religiosos no ordenados y apruebe la Ley de Protecci\u00f3n de la Fuerza Laboral Religiosa.<\/p><p>La carta advierte que la incertidumbre actual afecta directamente a congregaciones e instituciones religiosas. \u201cSacerdotes, hermanas religiosas y otros est\u00e1n siendo obligados a abandonar sus ministerios a pesar de tener una base legal v\u00e1lida para permanecer\u201d, se\u00f1ala el documento.<\/p><h3>Restricciones migratorias separan familias<\/h3><p>Los obispos expresan preocupaci\u00f3n por las restricciones migratorias basadas en nacionalidad que afectan a ciudadanos de decenas de pa\u00edses. Seg\u00fan la carta, estas medidas \u201cmantienen injustamente separadas a familias\u201d y colocan a muchas personas en riesgo de perder su estatus migratorio pese a sus esfuerzos por cumplir con la ley.<\/p><p>El documento pide fortalecer los mecanismos de supervisi\u00f3n dentro del DHS para garantizar transparencia, protecci\u00f3n de derechos civiles y confianza p\u00fablica en el sistema migratorio.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-bf8c21b e-flex e-con-boxed e-con e-parent\" data-id=\"bf8c21b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fac1f5c elementor-grid-eael-col-1 elementor-grid-tablet-eael-col-2 elementor-grid-mobile-eael-col-1 elementor-widget elementor-widget-eael-post-grid\" data-id=\"fac1f5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;eael_post_grid_columns&quot;:&quot;eael-col-1&quot;,&quot;eael_post_grid_columns_tablet&quot;:&quot;eael-col-2&quot;,&quot;eael_post_grid_columns_mobile&quot;:&quot;eael-col-1&quot;}\" data-widget_type=\"eael-post-grid.default\">\n\t\t\t\t\t<div id=\"eael-post-grid-fac1f5c\" class=\"eael-post-grid-container\">\n            <div class=\"eael-post-grid eael-post-appender eael-post-appender-fac1f5c eael-post-grid-style-one\" data-layout-mode=\"masonry\"><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-54795 category-noticias\" data-id=\"54795\">\n        <div class=\"eael-grid-post-holder\">\n            <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"far fa-hand-pointer\" aria-hidden=\"true\"><\/i><a href=\"https:\/\/soymigrante.com\/revista\/detencion-de-migrantes-sin-record-criminal-sube-800-por-ciento\/\"><\/a><\/div><div class=\"eael-entry-thumbnail eael-image-ratio\">\n                <img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2026\/04\/deportaciones-ice-1024x1024.jpg\" class=\"attachment-large size-large wp-image-54796\" alt=\"deportaciones ice\" srcset=\"https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2026\/04\/deportaciones-ice-1024x1024.jpg 1024w, https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2026\/04\/deportaciones-ice-300x300.jpg 300w, https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2026\/04\/deportaciones-ice-150x150.jpg 150w, https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2026\/04\/deportaciones-ice-768x768.jpg 768w, https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2026\/04\/deportaciones-ice-75x75.jpg 75w, https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2026\/04\/deportaciones-ice-750x750.jpg 750w, https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2026\/04\/deportaciones-ice-1140x1140.jpg 1140w, https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2026\/04\/deportaciones-ice.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\n            <\/div>\n        <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"https:\/\/soymigrante.com\/revista\/detencion-de-migrantes-sin-record-criminal-sube-800-por-ciento\/\" title=\"Detenci\u00f3n de migrantes sin r\u00e9cord criminal en USA ha subido 800%: Deportation Data Project\">Detenci\u00f3n de migrantes sin r\u00e9cord criminal en USA ha subido 800%: Deportation Data Project<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                        <div class=\"eael-grid-post-excerpt\"><a href=\"https:\/\/soymigrante.com\/revista\/detencion-de-migrantes-sin-record-criminal-sube-800-por-ciento\/\" class=\"eael-post-elements-readmore-btn\">CONOCE SU HISTORIA <\/a><\/div>\n                    <\/div><\/div><\/div>\n        <\/div>\n    <\/article><\/div>\n            <div class=\"clearfix\"><\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-89bcdff e-flex e-con-boxed e-con e-parent\" data-id=\"89bcdff\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5964ff4 elementor-widget elementor-widget-text-editor\" data-id=\"5964ff4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000; font-family: Mulish, sans-serif; font-size: 29px; font-weight: bold;\">Preocupaci\u00f3n por los retrasos que afectan a los Dreamers<\/span><\/p><p>La situaci\u00f3n de los beneficiarios de <a href=\"https:\/\/en.wikipedia.org\/wiki\/Deferred_Action_for_Childhood_Arrivals\" target=\"_blank\" rel=\"noopener\">DACA<\/a>, conocidos como Dreamers, ocupa una parte importante de la carta.<\/p><p>Los obispos advierten que los retrasos en la renovaci\u00f3n de permisos est\u00e1n provocando que algunos beneficiarios pierdan autorizaci\u00f3n para trabajar o acumulen presencia irregular aun cuando presentaron sus solicitudes con suficiente anticipaci\u00f3n.<\/p><p>\u201cAlgunos beneficiarios de DACA est\u00e1n perdiendo sus permisos de trabajo y acumulando presencia ilegal debido a demoras excesivas en el procesamiento\u201d, se\u00f1ala el documento.<\/p><p>Cahill pidi\u00f3 al Congreso impulsar una soluci\u00f3n legislativa permanente para los Dreamers y exigir respuestas sobre los retrasos administrativos.<\/p><h3>Defensa de refugiados y menores migrantes<\/h3><p>La carta agradece que la administraci\u00f3n federal retirara una propuesta que contemplaba reducciones significativas en los programas de asistencia para refugiados y otras poblaciones humanitarias.<\/p><p>Los obispos solicitaron mantener los fondos destinados a refugiados, asilados, v\u00edctimas de trata y otros grupos vulnerables al menos en los niveles aprobados para 2026.<\/p><p>Seg\u00fan el documento, estos programas permiten a miles de personas \u201creconstruir sus vidas y alcanzar estabilidad econ\u00f3mica\u201d despu\u00e9s de haber sufrido persecuci\u00f3n, violencia o desplazamiento forzado.<\/p><p>La Conferencia de Obispos tambi\u00e9n respald\u00f3 la ampliaci\u00f3n de servicios para menores migrantes no acompa\u00f1ados, incluidos programas de asistencia legal y seguimiento posterior a su liberaci\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-60cf89e e-flex e-con-boxed e-con e-parent\" data-id=\"60cf89e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8246c53 elementor-widget elementor-widget-html\" data-id=\"8246c53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<iframe width=\"560\" height=\"415\" src=\"https:\/\/www.youtube.com\/embed\/icobBwg3cwU?si=Hly1Kia0RjSJf1gV\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-239caae e-flex e-con-boxed e-con e-parent\" data-id=\"239caae\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4c56652 elementor-widget elementor-widget-text-editor\" data-id=\"4c56652\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000; font-family: Mulish, sans-serif; font-size: 29px; font-weight: bold;\">\u201cProfundamente preocupados\u201d por las restricciones a refugiados<\/span><\/p><p>Uno de los pasajes m\u00e1s contundentes de la carta se refiere al sistema estadounidense de reasentamiento de refugiados.<\/p><p>\u201cEstamos profundamente preocupados por la manera en que las restricciones actuales impiden que los refugiados m\u00e1s vulnerables sean reasentados en Estados Unidos\u201d, escribi\u00f3 Cahill.<\/p><p>Los obispos destacaron especialmente la situaci\u00f3n de personas perseguidas por motivos religiosos y solicitaron preservar los programas de reasentamiento y renovar la Enmienda Lautenberg, utilizada durante d\u00e9cadas para proteger a minor\u00edas religiosas perseguidas.<\/p><p>Asimismo, pidieron mantener una s\u00f3lida financiaci\u00f3n para programas internacionales de ayuda humanitaria destinados a atender las causas que impulsan la migraci\u00f3n forzada.<\/p><h3>\u201cNos oponemos a la deportaci\u00f3n masiva indiscriminada\u201d<\/h3><p>La secci\u00f3n dedicada a las deportaciones contiene algunas de las declaraciones m\u00e1s fuertes de todo el documento.<\/p><p>\u201cNos oponemos a la deportaci\u00f3n masiva indiscriminada de personas\u201d, recuerda la carta al citar una posici\u00f3n previamente adoptada por los obispos estadounidenses. El Comit\u00e9 de Migraci\u00f3n afirma que las medidas recientes han incrementado las preocupaciones relacionadas con el debido proceso, la separaci\u00f3n familiar y posibles pr\u00e1cticas discriminatorias.<\/p><p>Por ello, los obispos piden al Congreso evitar nuevas expansiones presupuestarias destinadas a detenci\u00f3n y deportaci\u00f3n. \u201cDadas estas circunstancias y la financiaci\u00f3n sin precedentes para la aplicaci\u00f3n de las leyes migratorias y la detenci\u00f3n proporcionada por la legislaci\u00f3n aprobada el a\u00f1o pasado, pedimos nuevamente al Congreso que limite cualquier aumento adicional de fondos para estos prop\u00f3sitos\u201d, se\u00f1ala la carta.<\/p><h3>Cr\u00edticas al regreso de la detenci\u00f3n familiar<\/h3><p>Los obispos tambi\u00e9n rechazaron la posibilidad de ampliar el uso de centros de detenci\u00f3n familiar.<\/p><p>La carta cita declaraciones previas de Cahill sobre este tema:<\/p><p>\u201cLa idea de mantener a miles de familias en enormes almacenes deber\u00eda desafiar la conciencia de cada estadounidense\u201d.<\/p><p>El documento solicita fortalecer la supervisi\u00f3n de cualquier instalaci\u00f3n destinada a familias migrantes y favorecer alternativas comunitarias.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-de5a220 e-flex e-con-boxed e-con e-parent\" data-id=\"de5a220\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-227b931 elementor-widget elementor-widget-html\" data-id=\"227b931\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<iframe width=\"560\" height=\"415\" src=\"https:\/\/www.youtube.com\/embed\/7TcC_lf9TWY?si=P4JZSuqmy7dtdJAX\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-1288a31 e-flex e-con-boxed e-con e-parent\" data-id=\"1288a31\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e0364eb elementor-widget elementor-widget-text-editor\" data-id=\"e0364eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000; font-family: Mulish, sans-serif; font-size: 29px; font-weight: bold;\">Iglesias, asistencia religiosa y representaci\u00f3n legal<\/span><\/p><p>La Conferencia de Obispos pidi\u00f3 que las operaciones migratorias respeten iglesias y otros lugares sensibles donde las personas buscan apoyo espiritual o comunitario.<\/p><p>Tambi\u00e9n solicit\u00f3 garantizar acceso continuo a servicios religiosos para las personas detenidas y restaurar programas federales de orientaci\u00f3n legal para inmigrantes.<\/p><p>Seg\u00fan la carta, estos programas contribuyen a procesos m\u00e1s justos y ayudan a combatir fraudes cometidos por falsos asesores migratorios.<\/p><h3>M\u00e1s recursos contra la trata y la explotaci\u00f3n laboral<\/h3><p>En la parte final del documento, los obispos instan al Congreso a aumentar los recursos destinados a combatir la <a href=\"https:\/\/en.wikipedia.org\/wiki\/Human_trafficking\" target=\"_blank\" rel=\"noopener\">trata de personas<\/a>, el trabajo infantil y otras formas de explotaci\u00f3n laboral.<\/p><p>La carta respalda mayores fondos para las agencias encargadas de supervisar condiciones de trabajo y proteger a poblaciones vulnerables tanto dentro como fuera de Estados Unidos.<\/p><p>Al concluir, Cahill recuerda el principio que gu\u00eda la posici\u00f3n de la Iglesia en materia migratoria: \u201ccada persona es creada a imagen y semejanza de Dios\u201d. A partir de esa convicci\u00f3n, los obispos instan al Congreso a que las decisiones presupuestarias sobre inmigraci\u00f3n combinen seguridad, legalidad y protecci\u00f3n de los derechos fundamentales de las personas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-f46adfb e-flex e-con-boxed e-con e-parent\" data-id=\"f46adfb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-717c8a3 elementor-widget elementor-widget-image\" data-id=\"717c8a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2025\/01\/Huehuetenango-4-1024x682.jpeg\" class=\"attachment-large size-large wp-image-20214\" alt=\"El obispo Brendan Cahill, de Victoria, Texas es quien suscribe la carta enviada a congresistas republicanos y dem\u00f3cratas del comit\u00e9 de apropiaciones del Congreso, de cara a las solicitudes de m\u00e1s presupuesto para operativos de deportaci\u00f3n para el pr\u00f3ximo presupuesto.\" srcset=\"https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2025\/01\/Huehuetenango-4-1024x682.jpeg 1024w, https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2025\/01\/Huehuetenango-4-300x200.jpeg 300w, https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2025\/01\/Huehuetenango-4-768x512.jpeg 768w, https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2025\/01\/Huehuetenango-4-1536x1024.jpeg 1536w, https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2025\/01\/Huehuetenango-4-750x500.webp 750w, https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2025\/01\/Huehuetenango-4-1140x760.webp 1140w, https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2025\/01\/Huehuetenango-4.jpeg 2000w\" sizes=\"(max-width: 768px) 100vw, 768px\" title=\"El obispo Brendan Cahill, de Victoria, Texas es quien suscribe la carta enviada a congresistas republicanos y dem\u00f3cratas del comit\u00e9 de apropiaciones del Congreso, de cara a las solicitudes de m\u00e1s presupuesto para operativos de deportaci\u00f3n para el pr\u00f3ximo presupuesto. \u2013 SoyMigrante.com REVISTA\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">En 2019, Oswaldo Mart\u00edn regres\u00f3 a su natal Todos Santos Cuchumat\u00e1n y particip\u00f3 en las famosas carreras ceremoniales del 1 de noviembre: a pesar del tiempo y la distancia, su identidad es su fortaleza e inspiraci\u00f3n para apoyar a los migrantes guatemaltecos, mayas, mam y de otros pueblos. (Foto cortes\u00eda Oswaldo Martin)<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Obispos de Estados Unidos piden al Congreso limitar fondos para deportaciones, reforzar protecci\u00f3n a familias migrantes y emprender una transformaci\u00f3n del sistema migratorio. \u201cDadas las circunstancias y la financiaci\u00f3n sin precedentes para la aplicaci\u00f3n de las leyes migratorias y la detenci\u00f3n proporcionada por la legislaci\u00f3n aprobada el a\u00f1o pasado, pedimos nuevamente al Congreso que limite [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":57425,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_eb_attr":"","footnotes":""},"categories":[280],"tags":[],"class_list":["post-57424","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Seg\u00fan datos oficiales de ICE analizados en Deportation Data Project la detenci\u00f3n de personas indocumentadas pero sin r\u00e9cord criminal en USA se multiplic\u00f3 por 8\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"SoyMigrante.com REVISTA\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/soymigrante.com\/revista\/detencion-de-migrantes-sin-record-criminal-sube-800-por-ciento\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\n\t\t<link rel=\"preconnect\" href=\"https:\/\/fonts.googleapis.com\" crossorigin>\n<link rel=\"preconnect\" href=\"https:\/\/fonts.gstatic.com\" crossorigin>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"SoyMigrante.com REVISTA \u2013 Nuestra misi\u00f3n es reconocer y dignificar al migrante.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"800% creci\u00f3 detenci\u00f3n de migrantes sin r\u00e9cord criminal\" \/>\n\t\t<meta property=\"og:description\" content=\"Seg\u00fan datos oficiales de ICE analizados en Deportation Data Project la detenci\u00f3n de personas indocumentadas pero sin r\u00e9cord criminal en USA se multiplic\u00f3 por 8\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/soymigrante.com\/revista\/detencion-de-migrantes-sin-record-criminal-sube-800-por-ciento\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2026\/04\/deportaciones-ice.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2026\/04\/deportaciones-ice.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-04-10T17:36:44+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-04-10T19:12:12+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/soymigrantecom\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@SoyMigrante_com\" \/>\n\t\t<meta name=\"twitter:title\" content=\"800% creci\u00f3 detenci\u00f3n de migrantes sin r\u00e9cord criminal\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Seg\u00fan datos oficiales de ICE analizados en Deportation Data Project la detenci\u00f3n de personas indocumentadas pero sin r\u00e9cord criminal en USA se multiplic\u00f3 por 8\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@SoyMigrante_com\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2026\/04\/deportaciones-ice.jpg\" \/>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>800% creci\u00f3 detenci\u00f3n de migrantes sin r\u00e9cord criminal<\/title>\n\n","aioseo_head_json":{"title":"800% creci\u00f3 detenci\u00f3n de migrantes sin r\u00e9cord criminal","description":"Seg\u00fan datos oficiales de ICE analizados en Deportation Data Project la detenci\u00f3n de personas indocumentadas pero sin r\u00e9cord criminal en USA se multiplic\u00f3 por 8","canonical_url":"https:\/\/soymigrante.com\/revista\/detencion-de-migrantes-sin-record-criminal-sube-800-por-ciento\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":"&lt;link rel=\"preconnect\" href=\"https:\/\/fonts.googleapis.com\" crossorigin&gt;\n&lt;link rel=\"preconnect\" href=\"https:\/\/fonts.gstatic.com\" crossorigin&gt;"},"schema":null,"og:locale":"es_ES","og:site_name":"SoyMigrante.com REVISTA \u2013 Nuestra misi\u00f3n es reconocer y dignificar al migrante.","og:type":"article","og:title":"800% creci\u00f3 detenci\u00f3n de migrantes sin r\u00e9cord criminal","og:description":"Seg\u00fan datos oficiales de ICE analizados en Deportation Data Project la detenci\u00f3n de personas indocumentadas pero sin r\u00e9cord criminal en USA se multiplic\u00f3 por 8","og:url":"https:\/\/soymigrante.com\/revista\/detencion-de-migrantes-sin-record-criminal-sube-800-por-ciento\/","og:image":"https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2026\/04\/deportaciones-ice.jpg","og:image:secure_url":"https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2026\/04\/deportaciones-ice.jpg","og:image:width":1200,"og:image:height":1200,"article:published_time":"2026-04-10T17:36:44+00:00","article:modified_time":"2026-04-10T19:12:12+00:00","article:publisher":"https:\/\/www.facebook.com\/soymigrantecom","twitter:card":"summary_large_image","twitter:site":"@SoyMigrante_com","twitter:title":"800% creci\u00f3 detenci\u00f3n de migrantes sin r\u00e9cord criminal","twitter:description":"Seg\u00fan datos oficiales de ICE analizados en Deportation Data Project la detenci\u00f3n de personas indocumentadas pero sin r\u00e9cord criminal en USA se multiplic\u00f3 por 8","twitter:creator":"@SoyMigrante_com","twitter:image":"https:\/\/soymigrante.com\/revista\/wp-content\/uploads\/2026\/04\/deportaciones-ice.jpg"},"aioseo_meta_data":{"post_id":"57424","title":"Obispos USA piden al Congreso transformar abordaje migratorio","description":"Carta a congresistas pide frenar separaci\u00f3n de familias, mejorar DACA y cambiar el sistema migratorio para humanizarlo, de cara a impactos de actual pol\u00edtica","keywords":null,"keyphrases":{"focus":{"keyphrase":"Obispos","score":82},"additional":[{"keyphrase":"USA","score":74},{"keyphrase":"migratorio","score":74}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"NewsArticle","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2026-06-24 17:49:49","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":"0","open_ai":null,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-06-03 15:43:59","updated":"2026-08-27 22:00:06","focus_keyword":"Obispos","additional_keywords":[{"word":"USA","score":74,"items":{"introductionKeyword":{"score":3},"keyphraseLength":{"score":9},"keyphraseDensity":{"score":4},"functionWordsInKeyphrase":{"score":9},"textCompetingLinks":{"score":9},"imageKeyphrase":{"score":6}}},{"word":"migratorio","score":74,"items":{"introductionKeyword":{"score":3},"keyphraseLength":{"score":9},"keyphraseDensity":{"score":4},"functionWordsInKeyphrase":{"score":9},"textCompetingLinks":{"score":9},"imageKeyphrase":{"score":6}}}],"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/soymigrante.com\/revista\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/soymigrante.com\/revista\/category\/noticias\/\" title=\"Noticias\">Noticias<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\tObispos de USA piden al Congreso transformar abordaje migratorio y frenar la separaci\u00f3n de familias\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/soymigrante.com\/revista"},{"label":"Noticias","link":"https:\/\/soymigrante.com\/revista\/category\/noticias\/"},{"label":"Obispos de USA piden al Congreso transformar abordaje migratorio y frenar la separaci\u00f3n de familias","link":"https:\/\/soymigrante.com\/revista\/obispos-de-usa-piden-al-congreso-transformar-abordaje-migratorio-y-frenar-la-separacion-de-familias\/"}],"_links":{"self":[{"href":"https:\/\/soymigrante.com\/revista\/wp-json\/wp\/v2\/posts\/57424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soymigrante.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/soymigrante.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/soymigrante.com\/revista\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/soymigrante.com\/revista\/wp-json\/wp\/v2\/comments?post=57424"}],"version-history":[{"count":0,"href":"https:\/\/soymigrante.com\/revista\/wp-json\/wp\/v2\/posts\/57424\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/soymigrante.com\/revista\/wp-json\/wp\/v2\/media\/57425"}],"wp:attachment":[{"href":"https:\/\/soymigrante.com\/revista\/wp-json\/wp\/v2\/media?parent=57424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/soymigrante.com\/revista\/wp-json\/wp\/v2\/categories?post=57424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/soymigrante.com\/revista\/wp-json\/wp\/v2\/tags?post=57424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}